{"id":1250,"date":"2020-01-01T23:10:00","date_gmt":"2020-01-02T02:10:00","guid":{"rendered":"https:\/\/www.cuatrogiros.com\/4G\/?p=1250"},"modified":"2020-05-11T04:28:11","modified_gmt":"2020-05-11T07:28:11","slug":"que-es-el-coronavirus","status":"publish","type":"post","link":"https:\/\/www.cuatrogiros.com\/4G\/que-es-el-coronavirus\/","title":{"rendered":"\u00bfQu\u00e9 es el Coronavirus?"},"content":{"rendered":"\n<p><strong>El Coronavirus pertenece a una gran familia de virus que generan en los seres humanos varias enfermedades,<\/strong> la m\u00e1s mortal por el momento es <strong>SRAS<\/strong> <em>(S\u00edndrome Respiratorio Agudo Severo)<\/em> o <strong>SRMO<\/strong> <em>(S\u00edndrome Respiratorio de Medio Oriente)<\/em>.<\/p>\n\n\n\n<p>Se descubri\u00f3 reci\u00e9n en\n2012 en Arabia Saudita que la cepa del virus pod\u00eda ser mortal, pero no se hizo\nconocida mundialmente por su baja cantidad de infectados y muertos que tuvo en esa\nfugaz aparici\u00f3n. <\/p>\n\n\n\n<p>Hasta que el 2019 se le informo a la OMS <em>(Organizaci\u00f3n Mundial de la Salud)<\/em> varios casos de neumon\u00eda en la ciudad de Wuhan, China, donde sus autoridades confirmaron la aparici\u00f3n de una nueva cepa de coronavirus.<\/p>\n\n\n\n<p>Habitualmente,\neste tipo de virus que puede ser m\u00e1s com\u00fan entre los animales, no se contagia a\nla poblaci\u00f3n, pero esta nueva variable de la familia del virus, la s\u00e9ptima en\naparecer, puede causar la muerte, incluso si es tratada a tiempo.<\/p>\n\n\n\n<p><strong>Las autoridades de la Salud a nivel mundial est\u00e1n en alerta y cooperando para el control de esta nueva enfermedad. <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Coronavirus pertenece a una gran familia de virus que generan en los seres humanos varias enfermedades, la m\u00e1s mortal por el momento es SRAS (S\u00edndrome Respiratorio Agudo Severo) o SRMO (S\u00edndrome Respiratorio de Medio Oriente). Se descubri\u00f3 reci\u00e9n en 2012 en Arabia Saudita que&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2632,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[75],"tags":[94,152],"_links":{"self":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/1250"}],"collection":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/comments?post=1250"}],"version-history":[{"count":1,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/1250\/revisions"}],"predecessor-version":[{"id":2642,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/1250\/revisions\/2642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media\/2632"}],"wp:attachment":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media?parent=1250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/categories?post=1250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/tags?post=1250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}