{"id":2491,"date":"2020-05-10T23:10:10","date_gmt":"2020-05-11T02:10:10","guid":{"rendered":"https:\/\/www.cuatrogiros.com\/4G\/?p=2491"},"modified":"2024-04-16T12:46:26","modified_gmt":"2024-04-16T15:46:26","slug":"que-significa-el-sol-la-luna-y-el-ascendente-en-nuestra-carta-natal","status":"publish","type":"post","link":"https:\/\/www.cuatrogiros.com\/4G\/que-significa-el-sol-la-luna-y-el-ascendente-en-nuestra-carta-natal\/","title":{"rendered":"\u00bfQu\u00e9 significa el Sol, la Luna y el Ascendente en nuestra Carta Natal?"},"content":{"rendered":"\n<p>La Carta Astral o Carta Natal es una representaci\u00f3n gr\u00e1fica que muestra exactamente d\u00f3nde estaban ubicados los planetas en el cielo en el momento en que nacimos. Es una gran herramienta de autoconocimiento que nos permite aprender no s\u00f3lo acerca de nuestra personalidad, sino tambi\u00e9n conocer nuestras potencialidades y debilidades. &nbsp;<\/p>\n\n\n\n<p>En nuestra carta, donde est\u00e1 el Sol es nuestro signo zodiacal, es la respuesta que damos cuando nos preguntan \u00bfde qu\u00e9 signo sos?&nbsp; Representa el Yo, la identidad, nuestra esencia,&nbsp; lo que nos hace especiales, la voluntad y el prop\u00f3sito de vida. Es nuestra autonom\u00eda.<\/p>\n\n\n\n<p>La Luna muestra las emociones y sentimientos. Es la que nos ense\u00f1a lo que necesitamos para regenerarnos, nutrirnos y sentir seguridad. Tiene que ver con nuestra madre y nuestro ni\u00f1o interior, con el hogar, la familia, la intuici\u00f3n, la feminidad y fecundidad.<\/p>\n\n\n\n<p>Junto con los dos anteriores, el Ascendente completa los tres aspectos m\u00e1s importantes de la carta astral y simboliza nuestra apariencia y personalidad. Es c\u00f3mo los dem\u00e1s nos ven y c\u00f3mo nosotros vemos el mundo. Es el filtro que usamos para ver las cosas.&nbsp; Tambi\u00e9n nos habla del cuerpo f\u00edsico, la forma en que nos vestimos y c\u00f3mo nos mostramos. Las caracter\u00edsticas de nuestro signo ascendente las vamos aprendiendo e integrando con las personas y situaciones que atraemos en nuestra vida.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Carta Astral o Carta Natal es una representaci\u00f3n gr\u00e1fica que muestra exactamente d\u00f3nde estaban ubicados los planetas en el cielo en el momento en que nacimos. Es una gran herramienta de autoconocimiento que nos permite aprender no s\u00f3lo acerca de nuestra personalidad, sino tambi\u00e9n&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2359,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51],"tags":[84],"_links":{"self":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/2491"}],"collection":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/comments?post=2491"}],"version-history":[{"count":1,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/2491\/revisions"}],"predecessor-version":[{"id":2494,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/2491\/revisions\/2494"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media\/2359"}],"wp:attachment":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media?parent=2491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/categories?post=2491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/tags?post=2491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}