{"id":2923,"date":"2020-05-27T20:17:33","date_gmt":"2020-05-27T23:17:33","guid":{"rendered":"https:\/\/www.cuatrogiros.com\/4G\/?p=2923"},"modified":"2020-05-28T00:54:16","modified_gmt":"2020-05-28T03:54:16","slug":"femicidio-de-anahi-benitez-condenaron-a-marcos-bazan","status":"publish","type":"post","link":"https:\/\/www.cuatrogiros.com\/4G\/femicidio-de-anahi-benitez-condenaron-a-marcos-bazan\/","title":{"rendered":"Femicidio de Anah\u00ed Ben\u00edtez: condenaron a Marcos Baz\u00e1n"},"content":{"rendered":"\n<p>Agosto de 2017. Otra vez. Una mujer m\u00e1s. Una adolescente. Otra m\u00e1s. Un nombre m\u00e1s por el que pedir Justicia. Por el que seguir gritando, basta ya. Anah\u00ed ten\u00eda 16 a\u00f1os y estuvo desaparecida durante seis d\u00edas, entre el 29 de julio y el 4 de agosto, cuando finalmente fue encontrada sin vida en la reserva de Santa Catalina, en Lomas de Zamora.<\/p>\n\n\n\n<p>Por el crimen hay un \u00fanico detenido, Marcos Baz\u00e1n, quien en la ma\u00f1ana de hoy fue condenado por el Tribunal Oral en lo Criminal N\u00b0 7 y que espera su sentencia el pr\u00f3ximo martes 2 de junio.\u00a0 El acusado est\u00e1 detenido en la Unidad 9 de La Plata desde donde conoci\u00f3 el veredicto a trav\u00e9s de una videoconferencia.<\/p>\n\n\n\n<p><em>\u00abSi digo que estoy feliz, miento. Nada de esto me pone feliz. S\u00ed, estoy un poco aliviada porque el primero ya cay\u00f3\u00bb<\/em>,\u00a0<strong>dijo a la Agencia Nacional de Noticias T\u00e9lam<\/strong>, Silvia P\u00e9rez, la mam\u00e1 de la adolescente.<\/p>\n\n\n\n<p>Y es que, en un proceso judicial te\u00f1ido de irregularidades, el otro sospechoso, Marcelo Sergio Villalba dej\u00f3 de ser juzgado luego de que concluyeran que ten\u00eda<em> \u201cproblemas psiqui\u00e1tricos\u201d<\/em>.\u00a0 Sin embargo, Villalba fue se\u00f1alado como uno de los secuestradores, su ADN encontrado en el cuerpo de Anah\u00ed, y el celular de la joven (con un nuevo chip) en manos de uno de sus hijos. \u00a0\u00a0<\/p>\n\n\n\n<p><em>\u201cDeseo que Baz\u00e1n recapacite y alg\u00fan d\u00eda se digne a decir la verdad, aunque no creo que lo haga\u201d<\/em> expres\u00f3 la mam\u00e1 de la estudiante al tiempo que asegur\u00f3:<em> \u201cEste juicio no tiene un premio que es volver a ver a mi hija (\u2026) S\u00ed que cay\u00f3 uno, s\u00ed que faltan los dem\u00e1s y s\u00ed que van a caer uno por uno.\u00bb<\/em><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Agosto de 2017. Otra vez. Una mujer m\u00e1s. Una adolescente. Otra m\u00e1s. Un nombre m\u00e1s por el que pedir Justicia. Por el que seguir gritando, basta ya. Anah\u00ed ten\u00eda 16 a\u00f1os y estuvo desaparecida durante seis d\u00edas, entre el 29 de julio y el 4&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2925,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64,68],"tags":[111,124],"_links":{"self":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/2923"}],"collection":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/comments?post=2923"}],"version-history":[{"count":2,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/2923\/revisions"}],"predecessor-version":[{"id":2927,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/2923\/revisions\/2927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media\/2925"}],"wp:attachment":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media?parent=2923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/categories?post=2923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/tags?post=2923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}