{"id":3079,"date":"2020-06-04T22:24:17","date_gmt":"2020-06-05T01:24:17","guid":{"rendered":"https:\/\/www.cuatrogiros.com\/4G\/?p=3079"},"modified":"2020-06-08T13:08:42","modified_gmt":"2020-06-08T16:08:42","slug":"21-dias-mas-de-cuarentena-en-frases-de-axel-kicillof","status":"publish","type":"post","link":"https:\/\/www.cuatrogiros.com\/4G\/21-dias-mas-de-cuarentena-en-frases-de-axel-kicillof\/","title":{"rendered":"21 D\u00edas m\u00e1s de cuarentena en frases de Axel Kicillof"},"content":{"rendered":"\n<p><strong>Compartimos el Top Five de las frases del <\/strong>Gobernador de la Provincia de Buenos Aires en la conferencia de prensa donde se anunci\u00f3 la extensi\u00f3n de la cuarentena.<\/p>\n\n\n\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/www.cuatrogiros.com\/4G\/wp-content\/uploads\/2020\/06\/21Dias-04-1024x575.jpg\" alt=\"\" class=\"wp-image-3078\" srcset=\"https:\/\/www.cuatrogiros.com\/4G\/wp-content\/uploads\/2020\/06\/21Dias-04-1024x575.jpg 1024w, https:\/\/www.cuatrogiros.com\/4G\/wp-content\/uploads\/2020\/06\/21Dias-04-680x382.jpg 680w, https:\/\/www.cuatrogiros.com\/4G\/wp-content\/uploads\/2020\/06\/21Dias-04-768x431.jpg 768w, https:\/\/www.cuatrogiros.com\/4G\/wp-content\/uploads\/2020\/06\/21Dias-04-570x320.jpg 570w, https:\/\/www.cuatrogiros.com\/4G\/wp-content\/uploads\/2020\/06\/21Dias-04-800x450.jpg 800w, https:\/\/www.cuatrogiros.com\/4G\/wp-content\/uploads\/2020\/06\/21Dias-04.jpg 1140w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><em>\u00abConciencia, responsabilidad y sobre todo solidaridad. Porque aunque a uno no le toque puede contagiar\u00bb<\/em><\/p>\n\n\n\n<p><em>\u00abEn el Gran Buenos Aires vamos a seguir como hasta ahora\u00bb<\/em><\/p>\n\n\n\n<p><em>\u00abMarchamos a que la aplicaci\u00f3n Cuidar sea obligatoria\u00bb<\/em><\/p>\n\n\n\n<p><em>\u00abMientas circule el virus hay que seguir tomando medidas de precauci\u00f3n\u00bb<\/em><\/p>\n\n\n\n<p><em>\u00abHay 61 municipios sin contagios desde hace 21 d\u00edas\u00bb<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Compartimos el Top Five de las frases del Gobernador de la Provincia de Buenos Aires en la conferencia de prensa donde se anunci\u00f3 la extensi\u00f3n de la cuarentena. \u00abConciencia, responsabilidad y sobre todo solidaridad. Porque aunque a uno no le toque puede contagiar\u00bb \u00abEn el&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3075,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[86,94,96],"_links":{"self":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/3079"}],"collection":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/comments?post=3079"}],"version-history":[{"count":1,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/3079\/revisions"}],"predecessor-version":[{"id":3080,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/3079\/revisions\/3080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media\/3075"}],"wp:attachment":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media?parent=3079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/categories?post=3079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/tags?post=3079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}