{"id":3203,"date":"2020-06-14T01:31:41","date_gmt":"2020-06-14T04:31:41","guid":{"rendered":"https:\/\/www.cuatrogiros.com\/4G\/?p=3203"},"modified":"2020-06-14T01:31:42","modified_gmt":"2020-06-14T04:31:42","slug":"messi-le-gano-al-mallorca","status":"publish","type":"post","link":"https:\/\/www.cuatrogiros.com\/4G\/messi-le-gano-al-mallorca\/","title":{"rendered":"Messi le gan\u00f3 al Mallorca"},"content":{"rendered":"\n<p>El Barcelona de Leonel Messi le gan\u00f3 4 a 0 al Mallorca y continua siendo el puntero de la liga espa\u00f1ola.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Barcelona de Leonel Messi le gan\u00f3 4 a 0 al Mallorca y continua siendo el puntero de la liga espa\u00f1ola.<\/p>\n","protected":false},"author":1,"featured_media":3204,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[215,109,184],"_links":{"self":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/3203"}],"collection":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/comments?post=3203"}],"version-history":[{"count":1,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/3203\/revisions"}],"predecessor-version":[{"id":3205,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/3203\/revisions\/3205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media\/3204"}],"wp:attachment":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media?parent=3203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/categories?post=3203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/tags?post=3203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}