{"id":3423,"date":"2020-07-02T18:42:46","date_gmt":"2020-07-02T21:42:46","guid":{"rendered":"https:\/\/www.cuatrogiros.com\/4G\/?p=3423"},"modified":"2020-08-09T13:06:02","modified_gmt":"2020-08-09T16:06:02","slug":"cuidado-con-el-perro-por-que-no-debemos-tocar-bocina-si-se-nos-cruza-uno-cuando-estamos-al-volante","status":"publish","type":"post","link":"https:\/\/www.cuatrogiros.com\/4G\/cuidado-con-el-perro-por-que-no-debemos-tocar-bocina-si-se-nos-cruza-uno-cuando-estamos-al-volante\/","title":{"rendered":"\u00a1Cuidado con el perro! Por qu\u00e9 no debemos tocar bocina si se nos cruza uno cuando estamos al volante"},"content":{"rendered":"\n<p><em>Informaci\u00f3n importante que tal vez conoc\u00e9s, pero tal vez no. Estar al volante de un auto y cruzarse un perro en el medio de la calle es una situaci\u00f3n bastante com\u00fan. \u00bfC\u00f3mo debemos actuar para proteger la vida del animal y la nuestra?<\/em><\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 hay que hacer cuando manejando te cruzas un animal en la calle o en la ruta? Empecemos por lo que NO hay que hacer: tocar bocina, y mucho menos tocarla fuerte, como si quisi\u00e9ramos hacerle entender al perro que lo que est\u00e1 haciendo es incorrecto. No lo va a entender y es muy probable que se asuste.<\/strong><\/p>\n\n\n\n<p>As\u00ed lo explica el Real Autom\u00f3vil Club de Espa\u00f1a (RACE), un prestigioso instituto de seguridad vial que llev\u00f3 a cabo pruebas con animales en situaciones simuladas de tr\u00e1nsito. Si un perro<em> (o gato, o el animal que fuera)<\/em> se asusta con el bocinazo, podr\u00eda realizar movimientos impredecibles. Y eso aumenta las chances de que otro conductor lo atropelle.<\/p>\n\n\n\n<p><em><strong>\u00abSi ten\u00e9s que pasar por al lado del animal, hacelo muy lentamente. Nunca se sabe c\u00f3mo puede reaccionar ya que suelen estar desorientados\u00bb<\/strong><\/em>, explica el organismo que tiene ya m\u00e1s de 100 a\u00f1os de antig\u00fcedad. Y de noche, es clave que, cuando nos cruzamos con un perro y no se mueve, cambiemos las luces bajas a las de posici\u00f3n para no encandilarlos y evitar as\u00ed que se queden quietos en el lugar.<\/p>\n\n\n\n<p>Cuando el accidente es inminente; es decir, cuando venimos a una velocidad que no nos permitir\u00eda detenernos antes de chocar al animal, el RACE recomienda evitar pegar un volantazo, sujetar el volante e intentar detener el auto en forma controlada pese al impacto.<\/p>\n\n\n\n<p>Es com\u00fan encontrar calcos en las lunetas de los autos que digan <em>\u00absi me cruzo un perro, freno\u00bb<\/em>, dado que para muchas personas, el amor por los animales est\u00e1 primero. Y es entendible, pero lo que deben saber es que, frenando bruscamente a velocidades altas o pegando un volantazo se exponen a consecuencias graves para su integridad f\u00edsica y la del resto de los conductores, m\u00e1s all\u00e1 del animal.<\/p>\n\n\n\n<p>Seg\u00fan un estudio del RACE, yendo a 80 km\/h un veh\u00edculo promedio puede detenerse por completo ante la aparici\u00f3n de un animal a 60 metros, aunque eso depender\u00e1 en gran parte de la condici\u00f3n del asfalto y del auto<em> (frenos, neum\u00e1ticos, balanceo, etc.)<\/em>, entre otras cuestiones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informaci\u00f3n importante que tal vez conoc\u00e9s, pero tal vez no. Estar al volante de un auto y cruzarse un perro en el medio de la calle es una situaci\u00f3n bastante com\u00fan. \u00bfC\u00f3mo debemos actuar para proteger la vida del animal y la nuestra? \u00bfQu\u00e9 hay&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3293,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,10],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/3423"}],"collection":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/comments?post=3423"}],"version-history":[{"count":1,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/3423\/revisions"}],"predecessor-version":[{"id":3424,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/3423\/revisions\/3424"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media\/3293"}],"wp:attachment":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media?parent=3423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/categories?post=3423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/tags?post=3423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}