{"id":3465,"date":"2020-07-07T15:45:00","date_gmt":"2020-07-07T18:45:00","guid":{"rendered":"https:\/\/www.cuatrogiros.com\/4G\/?p=3465"},"modified":"2020-07-09T15:47:26","modified_gmt":"2020-07-09T18:47:26","slug":"se-tatuo-la-cara-de-alberto-fernandez-y-despues-la-tatuaron-en-twitter","status":"publish","type":"post","link":"https:\/\/www.cuatrogiros.com\/4G\/se-tatuo-la-cara-de-alberto-fernandez-y-despues-la-tatuaron-en-twitter\/","title":{"rendered":"Se tatu\u00f3 la cara de Alberto Fern\u00e1ndez y despu\u00e9s la tatuaron en Twitter"},"content":{"rendered":"\n<p><em>La publicaci\u00f3n se hizo viral por el parecido del retrato del Presidente al popular Roberto Gal\u00e1n.<\/em><\/p>\n\n\n\n<p>La reflexi\u00f3n es que las redes no perdonan. <strong>Una decidi\u00f3 homenajear al Presidente Alberto Fern\u00e1ndez y tatuarse su rostro en el brazo. Sin embargo, la foto inesperadamente destap\u00f3 un debate: \u00bfEs AF o es Roberto Gal\u00e1n?<\/strong><\/p>\n\n\n\n<p>Todo comenz\u00f3 cuando una usuaria de Twitter public\u00f3 la imagen del tatuaje y escribi\u00f3: \u00abBuen d\u00eda, no puedo creer lo que veo, ayer en Comodoro\u00bb. Enseguida se viraliz\u00f3 y recibi\u00f3 miles de comentarios. Sin embargo, no hubo muchas cr\u00edticas ni elogios por el dibujo, sino que las respuestas fueron en relaci\u00f3n al parecido del mandatario con el reconocido presentador.<\/p>\n\n\n\n<p>Gal\u00e1n naci\u00f3 el 21 de febrero de 1917, fue locutor de radio, conductor, publicitario, cantante y uno de los fundadores de la Sociedad Argentina de Locutores. Hasta el verano de 2000, a\u00f1o en el que falleci\u00f3, trabaj\u00f3 como presentador del programa de televisi\u00f3n Si lo sabe, cante.<\/p>\n\n\n\n<p>En televisi\u00f3n tambi\u00e9n condujo Cine universal y coment\u00f3 los conciertos de Andr\u00e9s Segovia y Friedrich Gulda. Luego aquellos programas que lo catapultaron al \u00e9xito: Remates en TV, Compre la orquesta, Nace una estrella, Gane y aprenda y El show de Roberto Gal\u00e1n. En noviembre de 1971 estren\u00f3 el programa Yo me quiero casar, \u00bfy usted?, su mayor logro en la televisi\u00f3n argentina.<\/p>\n\n\n\n<p>La foto ya convertida en tendencia circul\u00f3 con distintas frases del conductor. El mandatario argentino, que suele responder mensajes en la red social del pajarito, a\u00fan no se pronunci\u00f3 al respecto, pero los usuarios lo arroban y no pierden la esperanza de que \u00e9l tambi\u00e9n se divierta.<\/p>\n\n\n\n<p>\u00bfSer\u00e1 que est\u00e1 ocupado resolviendo la pandemia versi\u00f3n nacional? Esta historia continuar\u00e1&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La publicaci\u00f3n se hizo viral por el parecido del retrato del Presidente al popular Roberto Gal\u00e1n. La reflexi\u00f3n es que las redes no perdonan. Una decidi\u00f3 homenajear al Presidente Alberto Fern\u00e1ndez y tatuarse su rostro en el brazo. Sin embargo, la foto inesperadamente destap\u00f3 un&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3466,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[166],"tags":[80,144],"_links":{"self":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/3465"}],"collection":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/comments?post=3465"}],"version-history":[{"count":1,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/3465\/revisions"}],"predecessor-version":[{"id":3467,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/3465\/revisions\/3467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media\/3466"}],"wp:attachment":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media?parent=3465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/categories?post=3465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/tags?post=3465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}