{"id":4437,"date":"2021-08-13T00:18:30","date_gmt":"2021-08-13T03:18:30","guid":{"rendered":"https:\/\/www.cuatrogiros.com\/4G\/?p=4437"},"modified":"2021-08-31T19:44:40","modified_gmt":"2021-08-31T22:44:40","slug":"pedi-un-deseo","status":"publish","type":"post","link":"https:\/\/www.cuatrogiros.com\/4G\/pedi-un-deseo\/","title":{"rendered":"Ped\u00ed un deseo"},"content":{"rendered":"\n<p>Y s\u00ed, hay que decirlo: est\u00e1n lloviendo estrellas y podremos disfrutar el espect\u00e1culo hasta este s\u00e1bado 14. Si bien, la lluvia de estrellas fugaces conocidas como Perseidas comenz\u00f3 el 17 de julio pasado y se extender\u00e1 hasta el pr\u00f3ximo 24 de agosto, la m\u00e1xima visibilidad ser\u00e1 hasta el s\u00e1bado. Eso s\u00ed, para ver pasar casi 150 meteoritos por hora vas a tener que buscar un lugar con poca contaminaci\u00f3n lum\u00ednica.<\/p>\n\n\n\n<p>Este fen\u00f3meno se produce todos los a\u00f1os durante los meses de julio y agosto, cuando nuestro planeta atraviesa los rastros de escombros dejados por el antiguo cometa Swift-Tuttle. Este cuerpo celeste de 26 kil\u00f3metros de di\u00e1metro orbita alrededor del Sol cada 133 a\u00f1os y sus peque\u00f1os restos se vuelven luminosos cuando llegan a la atm\u00f3sfera de la Tierra a 215.000 kil\u00f3metros por hora.\u00a0\u00a0<\/p>\n\n\n\n<p>Por suerte, este fen\u00f3meno se puede observar a simple vista y no se necesita de ning\u00fan equipo especial pero s\u00ed, los expertos recomienda buscar un espacio abierto, lejos de la contaminaci\u00f3n lum\u00ednica.<\/p>\n\n\n\n<p><strong>Emily Clay<\/strong>, especialista del Centro de Vuelo Espacial Marshall de la NASA explic\u00f3 que, para que la vista se pueda adaptar a la oscuridad y ver las estrellas fugaces\u00a0<em>\u00abhay que mirar hacia el cielo nocturno por unos 30 minutos as\u00ed los ojos se van adaptar a la oscuridad y se ver\u00e1n m\u00e1s meteoritos\u00bb.\u00a0<\/em>Adem\u00e1s, recomend\u00f3 alejarse del tel\u00e9fono y otras pantallas brillantes ya que afectan a la visi\u00f3n nocturna.\u00a0<\/p>\n\n\n\n<p>Por lo general, las estrellas fugaces se pueden ver en todo el cielo habiendo momentos de mayor o menor intensidad respecto a la cantidad de meteoros que se pueden observar.&nbsp;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Y s\u00ed, hay que decirlo: est\u00e1n lloviendo estrellas y podremos disfrutar el espect\u00e1culo hasta este s\u00e1bado 14. Si bien, la lluvia de estrellas fugaces conocidas como Perseidas comenz\u00f3 el 17 de julio pasado y se extender\u00e1 hasta el pr\u00f3ximo 24 de agosto, la m\u00e1xima visibilidad&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4438,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51],"tags":[84],"_links":{"self":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/4437"}],"collection":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/comments?post=4437"}],"version-history":[{"count":1,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/4437\/revisions"}],"predecessor-version":[{"id":4439,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/4437\/revisions\/4439"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media\/4438"}],"wp:attachment":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media?parent=4437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/categories?post=4437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/tags?post=4437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}