{"id":4447,"date":"2021-08-17T19:25:03","date_gmt":"2021-08-17T22:25:03","guid":{"rendered":"https:\/\/www.cuatrogiros.com\/4G\/?p=4447"},"modified":"2024-04-16T12:21:36","modified_gmt":"2024-04-16T15:21:36","slug":"de-las-maximas-a-merceditas-cuanto-hemos-aprendido-los-argentinos","status":"publish","type":"post","link":"https:\/\/www.cuatrogiros.com\/4G\/de-las-maximas-a-merceditas-cuanto-hemos-aprendido-los-argentinos\/","title":{"rendered":"De las m\u00e1ximas a Merceditas, \u00bfCu\u00e1nto hemos aprendido los argentinos?"},"content":{"rendered":"\n<p>Se cumplen 171 a\u00f1os del fallecimiento del <strong>General Don Jos\u00e9 de San Mart\u00edn<\/strong> y recordamos las 12 m\u00e1ximas que le dejo a su hija en 1825 para poder llevar adelante una vida de respeto y felicidad.<\/p>\n\n\n\n<p><strong>Jos\u00e9 de\u00a0San Mart\u00edn redact\u00f3 doce\u00a0m\u00e1ximas\u00a0para su hija de nueve a\u00f1os, Mercedes Tomasa de\u00a0San Mart\u00edn. <\/strong>El libertador, consider\u00f3 que eran un instrumento necesario para guiar a Merceditas, tras la muerte de su madre dos a\u00f1os antes, a ser una buena persona y poder desarrollar su vida en un marco de respeto y felicidad.<\/p>\n\n\n\n<p><strong>Las m\u00e1ximas fueron:<\/strong><\/p>\n\n\n\n<ul><li>Humanizar el car\u00e1cter y hacerlo sensible a\u00fan con los insectos que nos perjudican. Stern ha dicho a una Mosca abri\u00e9ndole la ventana para que saliese: \u00abAnda, pobre Animal, el Mundo es demasiado grande para nosotros dos.\u00bb<\/li><li>Inspirarla amor a la verdad y odio a la mentira.<\/li><li>Inspirarla gran Confianza y Amistad, pero uniendo el respeto.<\/li><li>Estimular en Mercedes la Caridad con los Pobres.<\/li><li>Respeto sobre la propiedad ajena.<\/li><li>Acostumbrarla a guardar un Secreto.<\/li><li>Inspirarla sentimientos de indulgencia hacia todas las Religiones.<\/li><li>Dulzura con los Criados, Pobres y Viejos.<\/li><li>Que hable poco y lo preciso.<\/li><li>Acostumbrarla a estar formal en la Mesa.<\/li><li>Amor al Aseo y desprecio al Lujo.<\/li><li>Inspirarla amor por la Patria y por la Libertad.<\/li><\/ul>\n\n\n\n<p>Hoy, llama la atenci\u00f3n leerlas porque lejos parecen estar de aplicaci\u00f3n en el contexto actual. Una sociedad donde reina la individualidad, la imposici\u00f3n de poder y la insensibilidad con el otro. La desconfianza, la mentira y la traici\u00f3n son acciones que aparecen como moneda corriente.<\/p>\n\n\n\n<p>El poco respeto, no solo a la propiedad ajena, sino al otro, por pensar distinto, por tener caracter\u00edsticas diferentes o producto de los estereotipos creados por una sociedad que lejos est\u00e1 de la que pensaba San Mart\u00edn al escribirle las m\u00e1ximas a su hija.<\/p>\n\n\n\n<p>\u00bfDesprecio al lujo? Probablemente sea un sentimiento que la mayor\u00eda de la poblaci\u00f3n no pueda sentir, porque lejos est\u00e1 de hablar de lujos, cuando en realidad el lujo hoy muchas veces se trata de lo debiera ser una necesidad b\u00e1sica.<\/p>\n\n\n\n<p>Que lejos que ha quedado hoy la posibilidad de pensar que 12 sencillas, pero fundamentales, m\u00e1ximas redactadas por el Libertador San Mart\u00edn, sean aplicadas. Que f\u00e1cil ser\u00eda poder vivir en una sociedad unida y arm\u00f3nica si la puesta en pr\u00e1ctica de estas l\u00edneas sea algo com\u00fan, pero que lejos parece que estamos de poder verlas en marcha.<\/p>\n\n\n\n<p>Habr\u00e1 que seguir haciendo hincapi\u00e9 en los ni\u00f1os en la escuela, contarles qui\u00e9n fue, qu\u00e9 hizo por Argentina y Am\u00e9rica, mostrarles las 12 m\u00e1ximas y mientras, hacer un cambio estructural para que puedan ellos, el futuro, ponerlas en pr\u00e1ctica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se cumplen 171 a\u00f1os del fallecimiento del General Don Jos\u00e9 de San Mart\u00edn y recordamos las 12 m\u00e1ximas que le dejo a su hija en 1825 para poder llevar adelante una vida de respeto y felicidad. Jos\u00e9 de\u00a0San Mart\u00edn redact\u00f3 doce\u00a0m\u00e1ximas\u00a0para su hija de nueve&#8230;<\/p>\n","protected":false},"author":4,"featured_media":4448,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,187],"tags":[185,207],"_links":{"self":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/4447"}],"collection":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/comments?post=4447"}],"version-history":[{"count":1,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/4447\/revisions"}],"predecessor-version":[{"id":4449,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/4447\/revisions\/4449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media\/4448"}],"wp:attachment":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media?parent=4447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/categories?post=4447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/tags?post=4447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}