{"id":4454,"date":"2021-08-19T11:07:00","date_gmt":"2021-08-19T14:07:00","guid":{"rendered":"https:\/\/www.cuatrogiros.com\/4G\/?p=4454"},"modified":"2021-08-31T19:43:53","modified_gmt":"2021-08-31T22:43:53","slug":"del-daguerrotipo-a-la-selfie-dia-internacional-de-la-fotografia","status":"publish","type":"post","link":"https:\/\/www.cuatrogiros.com\/4G\/del-daguerrotipo-a-la-selfie-dia-internacional-de-la-fotografia\/","title":{"rendered":"Del daguerrotipo a la selfie, d\u00eda internacional de la fotograf\u00eda"},"content":{"rendered":"\n<p><em><strong>El 19 de agosto, desde el 2007, se celebra el d\u00eda internacional de la fotograf\u00eda, en homenaje a la creaci\u00f3n del daguerrotipo, considerada la primera pr\u00e1ctica del proceso fotogr\u00e1fico.<\/strong><\/em><\/p>\n\n\n\n<p>El daguerrotipo, inventado por <strong>Niepce<\/strong> y <strong>Daguerre<\/strong> en 1837, consiste en la generaci\u00f3n de una imagen sobre una superficie de plata pulida, que hace las veces de espejo donde se refleja la imagen. Para economizar en aquella \u00e9poca, normalmente las placas eran de cobre plateado.<\/p>\n\n\n\n<p>El invento debe su nombre a su creador, Louis-Jacques-Mand\u00e9 Daguerre, quien en 1839 perfeccion\u00f3 la t\u00e9cnica de Joseph Nic\u00e9phore Ni\u00e9pce, con quien hab\u00eda trabajado hasta su fallecimiento.<\/p>\n\n\n\n<p>El 19 de agosto de 1839 la Academia de Ciencias de Francia anunci\u00f3 la invenci\u00f3n. Se present\u00f3 como un regalo de Francia permitiendo as\u00ed que todo el mundo pudiera usarlo libremente y sin patentes. Fue por iniciativa del fot\u00f3grafo australiano Korske Ara que se celebre este d\u00eda como el Internacional de la fotograf\u00eda y dicha idea fue adoptada por todo el mundo desde 2007.<\/p>\n\n\n\n<p>Han sido miles los retratos que pudieron observarse a partir de esta t\u00e9cnica. La posibilidad de ponerle rostro a la historia. Luego, el perfeccionamiento de las t\u00e9cnicas, permiti\u00f3 que la fotograf\u00eda sea una acci\u00f3n mucho m\u00e1s simple de realizar. Dejaron de ser cuadros, para convertirse en \u00e1lbum de fotos.<\/p>\n\n\n\n<p>Dif\u00edcilmente <strong>Louis-Jacques-Mand\u00e9 Daguerr<\/strong>e se haya imaginado que, en el siglo XXI, estar\u00edamos con c\u00e1maras digitales, con definici\u00f3n en 4K y ni hablar, que un tel\u00e9fono, m\u00f3vil, permitiera tener im\u00e1genes al instante y multiplicadas por decenas sin tener que demorar absolutamente ni un segundo para obtenerlas.<\/p>\n\n\n\n<p>El primer aparato de daguerrotipos en Buenos Aires fue tra\u00eddo por Gregorio Ibarra, due\u00f1o de la Librer\u00eda y Litograf\u00eda Argentina. En junio de 1843 en La Gaceta Mercantil Ibarra y John Elliot ofrecen el servicio de Daguerrotipo. El mensaje de Ibarra aseguraba que \u00aben el corto espacio de algunos minutos fija sobre una l\u00e1mina de plata la imagen de cualquier objeto\u00bb pudiendo reproducir as\u00ed \u00abretratos, vistas y planos\u00bb.<\/p>\n\n\n\n<p>As\u00ed es como hace 182 a\u00f1os surg\u00eda el daguerrotipo y hace 178 en Buenos Aires se ofrec\u00eda el servicio de retratos y escenas. Hoy, un celular, una selfie y ya est\u00e1 nuestra imagen dando vuelta por alguna historia de Instagram.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 19 de agosto, desde el 2007, se celebra el d\u00eda internacional de la fotograf\u00eda, en homenaje a la creaci\u00f3n del daguerrotipo, considerada la primera pr\u00e1ctica del proceso fotogr\u00e1fico. El daguerrotipo, inventado por Niepce y Daguerre en 1837, consiste en la generaci\u00f3n de una imagen&#8230;<\/p>\n","protected":false},"author":4,"featured_media":4458,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[267,212],"tags":[185],"_links":{"self":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/4454"}],"collection":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/comments?post=4454"}],"version-history":[{"count":1,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/4454\/revisions"}],"predecessor-version":[{"id":4459,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/4454\/revisions\/4459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media\/4458"}],"wp:attachment":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media?parent=4454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/categories?post=4454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/tags?post=4454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}