{"id":4584,"date":"2021-09-29T10:17:00","date_gmt":"2021-09-29T13:17:00","guid":{"rendered":"https:\/\/www.cuatrogiros.com\/4G\/?p=4584"},"modified":"2021-10-07T19:31:02","modified_gmt":"2021-10-07T22:31:02","slug":"proponen-una-ley-de-seguridad-privada-ante-el-incremento-de-hechos-delictivos","status":"publish","type":"post","link":"https:\/\/www.cuatrogiros.com\/4G\/proponen-una-ley-de-seguridad-privada-ante-el-incremento-de-hechos-delictivos\/","title":{"rendered":"Proponen una ley de seguridad privada ante el incremento de hechos delictivos"},"content":{"rendered":"\n<p><strong>En Buenos Aires se registra 1 delito cada 3 minutos,<\/strong> ante esto organizaciones proponen una ley nacional de seguridad privada que permita una articulaci\u00f3n con la Seguridad P\u00fablica.<\/p>\n\n\n\n<p>Los n\u00fameros de inseguridad, muestran que durante el 2020 s\u00f3lo en la ciudad de Buenos Aires se registraron 84.672 delitos, en este 2021, la provincia lleva contabilizados 511 casos diarios, es decir, uno cada tres minutos.<\/p>\n\n\n\n<p>Frente a esta situaci\u00f3n, entidades del sector, luchan por impulsar una ley nacional de seguridad privada, que tiene entre sus l\u00edneas la idea de la articulaci\u00f3n entre la Seguridad P\u00fablica y la Seguridad Privada, formando un sistema integral del que pueden fortalecerse la seguridad tanto de la ciudad como de las distintas provincias del pa\u00eds.<\/p>\n\n\n\n<p>Adem\u00e1s, miembros de organizaciones electr\u00f3nicas consideran distintas medidas para disminuir la inseguridad, como incluir los temas de seguridad desde el inicio de los proyectos edilicios o capacitar a los colaboradores de manera permanente. <em>\u201cLa incorporaci\u00f3n de tecnolog\u00eda es indispensable. El aumento de la automatizaci\u00f3n, del uso de las soluciones en la nube y de la inteligencia artificial aplicada a la seguridad, se convierten en los responsables de mejorar la calidad del servicio al cliente y la calidad laboral de los empleados. Adem\u00e1s, ayudan a reducir errores humanos y contar con respuestas m\u00e1s r\u00e1pidas\u201d<\/em>, explica <strong>Juan Pablo Coletti<\/strong>, Director of International Strategy Partner, Dahua Technology.<\/p>\n\n\n\n<p>Otro punto a favor de la tecnolog\u00eda son los beneficios financieros que presenta. Por ejemplo, ante el crecimiento del costo de mantenimiento de los vigiladores tradicionales, otras medidas de seguridad, tales como: t\u00f3tems de vigilancia o c\u00e1maras de seguridad, se convierten en mejores opciones.<\/p>\n\n\n\n<p>De esta forma, la industria de la seguridad privada busca sumar instrumentos que aporten eficacia, rapidez, y automatizaci\u00f3n en los procesos y servicios de los que dependen la seguridad y vida de cada ciudadano. Para ello aseguran que es necesaria la unificaci\u00f3n de los sistemas y la incorporaci\u00f3n de tecnolog\u00edas en cada sector del pa\u00eds, por lo cual se busca la sanci\u00f3n de la ley.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Buenos Aires se registra 1 delito cada 3 minutos, ante esto organizaciones proponen una ley nacional de seguridad privada que permita una articulaci\u00f3n con la Seguridad P\u00fablica. Los n\u00fameros de inseguridad, muestran que durante el 2020 s\u00f3lo en la ciudad de Buenos Aires se&#8230;<\/p>\n","protected":false},"author":4,"featured_media":4583,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[329,207],"_links":{"self":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/4584"}],"collection":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/comments?post=4584"}],"version-history":[{"count":1,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/4584\/revisions"}],"predecessor-version":[{"id":4585,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/4584\/revisions\/4585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media\/4583"}],"wp:attachment":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media?parent=4584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/categories?post=4584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/tags?post=4584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}