{"id":4725,"date":"2021-10-27T09:51:54","date_gmt":"2021-10-27T12:51:54","guid":{"rendered":"https:\/\/www.cuatrogiros.com\/4G\/?p=4725"},"modified":"2021-11-03T20:10:38","modified_gmt":"2021-11-03T23:10:38","slug":"el-etiquetado-frontal-es-ley","status":"publish","type":"post","link":"https:\/\/www.cuatrogiros.com\/4G\/el-etiquetado-frontal-es-ley\/","title":{"rendered":"El etiquetado frontal es Ley"},"content":{"rendered":"\n<p><em>Luego de varios idas y vueltas, la Ley que contempla el etiquetado frontal fue sancionada por amplia mayor\u00eda en la C\u00e1mara de Diputados<\/em>.<\/p>\n\n\n\n<p>En medio de una marat\u00f3nica sesi\u00f3n, con 200 votos a favor, 22 en contra y 16 abstenciones, la C\u00e1mara de Diputados aprob\u00f3 la Ley de Promoci\u00f3n de la Alimentaci\u00f3n Saludable, que contempla el etiquetado frontal de alimentos. <\/p>\n\n\n\n<p>Esta Ley busca marcar pautas para una alimentaci\u00f3n m\u00e1s saludable, estableciendo que deben etiquetarse los productos procedados y ultraprocesados que tengan exceso de sodio, az\u00facares, grasas saturadas, grasas totales y calor\u00edas. <\/p>\n\n\n\n<p>Para esto, se colocar\u00e1 un sello de color negro, que tendr\u00e1 un tama\u00f1o del 5% del total del envase, en el cual se muestre la informaci\u00f3n de qu\u00e9 componentes en exceso tiene.<\/p>\n\n\n\n<p>Quedan exceptuados del etiquetado el az\u00facar, la miel, los aceites vegetales, los huevos, las semillas y los frutos secos, de acuerdo a lo establecido por la normativa aprobada.<\/p>\n\n\n\n<p>A su vez, se aclar\u00f3 que los productos fabricados previo a la sanci\u00f3n de la Ley, podr\u00e1n continuar a la venta hasta tanto se termine el stock de dicha partida, debiendo contener el etiquetado en las partidas siguientes. <\/p>\n\n\n\n<p>Tambien se propone educaci\u00f3n alimentaria nutricional en los niveles inicial, primario y secundario de todo el pa\u00eds para concientizar de la importancia de desarrollar un estilo de alimentaci\u00f3n saludable, principalmente en los primeros a\u00f1os o a\u00f1os de crecimiento.<\/p>\n\n\n\n<p>Esta Ley es de suma importancia en un pa\u00eds donde m\u00e1s del 50% de la poblaci\u00f3n tiene exceso de peso y enfermedades como la hipertensi\u00f3n, la hiperglucemia y la misma obesidad generan aproximadamente 140 mil muertes promedio por a\u00f1o. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego de varios idas y vueltas, la Ley que contempla el etiquetado frontal fue sancionada por amplia mayor\u00eda en la C\u00e1mara de Diputados. En medio de una marat\u00f3nica sesi\u00f3n, con 200 votos a favor, 22 en contra y 16 abstenciones, la C\u00e1mara de Diputados aprob\u00f3&#8230;<\/p>\n","protected":false},"author":4,"featured_media":4726,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54,75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/4725"}],"collection":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/comments?post=4725"}],"version-history":[{"count":1,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/4725\/revisions"}],"predecessor-version":[{"id":4727,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/4725\/revisions\/4727"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media\/4726"}],"wp:attachment":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media?parent=4725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/categories?post=4725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/tags?post=4725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}