{"id":4772,"date":"2021-11-08T13:21:18","date_gmt":"2021-11-08T16:21:18","guid":{"rendered":"https:\/\/www.cuatrogiros.com\/4G\/?p=4772"},"modified":"2021-11-16T17:50:33","modified_gmt":"2021-11-16T20:50:33","slug":"el-factor-educacion-sexual-mas-alla-del-meme","status":"publish","type":"post","link":"https:\/\/www.cuatrogiros.com\/4G\/el-factor-educacion-sexual-mas-alla-del-meme\/","title":{"rendered":"El factor educaci\u00f3n sexual, m\u00e1s all\u00e1 del meme"},"content":{"rendered":"\n<p>Durante los \u00faltimos d\u00edas se viraliz\u00f3 una captura pantalla de una conversaci\u00f3n de WhatsApp entre una madre y su hijo que viajaba a Bariloche. En la misma se ve como la madre le consulta si con dos cajas de 12 preservativos le alcanzar\u00eda y el joven, en chiste, le dice que necesita otras tres. M\u00e1s all\u00e1 del meme o la gracia, lo importante a destacar es la confianza de madre e hijo para hablar de un tema tan importante para poder educar a los adolescentes. <\/p>\n\n\n\n<p>\u00abTe compr\u00e9 2 cajas de preservativo, de 12 cada una\u00bb, acompa\u00f1ado de una foto de la caja de condones. \u00abTe alcanzar\u00e1?\u00bb pregunta la madre, claramente en tono humor\u00edstico, a su hijo adolescente quien se encontraba por viajar a Bariloche. El joven, le respondi\u00f3 que necesitar\u00eda tres cajas m\u00e1s porque le calculaba tener al menos \u00ab4 relaciones por d\u00eda\u00bb. <\/p>\n\n\n\n<p>La amiga del muchacho, que fue quien viraliz\u00f3 el mensaje, lo hizo diciendo \u00abMi amigo se va a Bariloche y se ve que la madre es muy ambiciosa\u00bb. Pero m\u00e1s all\u00e1 del chiste o el meme, hay una cuesti\u00f3n mucho m\u00e1s importante: el factor educaci\u00f3n en un tema tan importante como lo es la sexualidad en adolescentes. <\/p>\n\n\n\n<p>En nuestro pa\u00eds, se vive constantemente en el marco del debate sobre la implementaci\u00f3n en su totalidad de la Educaci\u00f3n Sexual Integral (ESI), que es el derecho de chicos y chicas de todas las escuelas del pa\u00eds, en sus tres niveles: inicial, primaria, secundaria, sean privadas o estatales, confesionales o laicas, a recibir ense\u00f1anza que promueva saberes y habilidades para la toma de decisiones responsables y cr\u00edticas en relaci\u00f3n con los derechos de los&nbsp;ni\u00f1os, las ni\u00f1as y los\/as adolescentes&nbsp;al cuidado del propio cuerpo, las relaciones interpersonales, la informaci\u00f3n y la sexualidad.<\/p>\n\n\n\n<p>Son objetivos del Programa Nacional de Educaci\u00f3n Sexual Integral:<\/p>\n\n\n\n<ul><li>Incorporar la educaci\u00f3n sexual integral dentro de las propuestas educativas orientadas a la formaci\u00f3n arm\u00f3nica equilibrada y permanente de las personas.<\/li><li>Asegurar la transmisi\u00f3n de conocimientos pertinentes, precisos y confiables y actualizados sobre los distintos aspectos involucrados en la educaci\u00f3n sexual integral.<\/li><li>Promover actitudes responsables ante la sexualidad.<\/li><li>Prevenir los problemas relacionados con la salud en general y la salud sexual y reproductiva en particular.<\/li><li>Procurar igualdad de trato y oportunidades para mujeres y varones.<\/li><\/ul>\n\n\n\n<p>Volviendo al hecho que motiv\u00f3 la viralizaci\u00f3n en redes, en primer lugar es de destacar la confianza de la madre para ser ella quien le compra los preservativos a su hijo, en un gesto de concientizaci\u00f3n y cuidado. No es normal que esto ocurra y muchas veces por el miedo que poseen los padres en hablar sobre estos temas con sus hijos. <\/p>\n\n\n\n<p>En segundo lugar, el mensaje que genera de que los adolescentes pueden vivir su vida sexual plena, siempre que mantengan sus cuidados, m\u00e1s aun en contextos como un viaje de egresados en el cual la relaci\u00f3n sexual no est\u00e1 dada con una pareja estable, lo cual incrementa los riesgos de contraer Enfermedades de transmisi\u00f3n sexual. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante los \u00faltimos d\u00edas se viraliz\u00f3 una captura pantalla de una conversaci\u00f3n de WhatsApp entre una madre y su hijo que viajaba a Bariloche. En la misma se ve como la madre le consulta si con dos cajas de 12 preservativos le alcanzar\u00eda y el&#8230;<\/p>\n","protected":false},"author":4,"featured_media":4773,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/4772"}],"collection":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/comments?post=4772"}],"version-history":[{"count":2,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/4772\/revisions"}],"predecessor-version":[{"id":4807,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/4772\/revisions\/4807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media\/4773"}],"wp:attachment":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media?parent=4772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/categories?post=4772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/tags?post=4772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}