{"id":4950,"date":"2022-02-02T17:34:00","date_gmt":"2022-02-02T20:34:00","guid":{"rendered":"https:\/\/www.cuatrogiros.com\/4G\/?p=4950"},"modified":"2022-02-03T09:37:14","modified_gmt":"2022-02-03T12:37:14","slug":"de-los-creadores-de-la-noche-de-los-museos-llega-la-noche-de-las-vacunas","status":"publish","type":"post","link":"https:\/\/www.cuatrogiros.com\/4G\/de-los-creadores-de-la-noche-de-los-museos-llega-la-noche-de-las-vacunas\/","title":{"rendered":"De los creadores de \u201cLa noche de los museos\u201d, llega \u201cLa noche de las vacunas\u201d"},"content":{"rendered":"\n<p><em>En el conurbano bonaerense se realizar\u00e1n m\u00e1s de 100 postas, fijas e itinerantes, en diferentes puntos para llegar a un p\u00fablico diferente.<\/em><\/p>\n\n\n\n<p>Al igual que se hace con los museos cada a\u00f1o, el Gobierno de la Provincia de Buenos Aires anunci\u00f3 que este viernes 4 de febrero, a partir de las 20.00 hs, ser\u00e1 \u00abLa noche de las vacunas\u00bb. Esta, contar\u00e1 con postas de vacunaci\u00f3n distribuidas por diferentes barrios bonaerenses para \u00abllegar a un p\u00fablico distinto en condiciones distintas\u00bb, seg\u00fan explic\u00f3 Nicol\u00e1s Kreplak.<\/p>\n\n\n\n<p>En cada una de las postas se aplicar\u00e1n primeras, segundas dosis y refuerzos, sin la necesidad de tener turnos previos, a personas mayores de los 3 a\u00f1os de edad. La jornada contar\u00e1 con 50 postas fijas y 50 postas itinerantes que estar\u00e1n distribuidas estrat\u00e9gicamente por toda la Provincia de Buenos Aires.<\/p>\n\n\n\n<p>Al respecto, el ministro de Salud bonaerense cont\u00f3: \u00abSabemos que la vacunaci\u00f3n es la herramienta que tenemos para poder dar el paso adelante y para prepararnos al inicio de clases y la temporada de oto\u00f1o invierno en las mejores condiciones\u00bb, explic\u00f3 el ministro de Salud bonaerense.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el conurbano bonaerense se realizar\u00e1n m\u00e1s de 100 postas, fijas e itinerantes, en diferentes puntos para llegar a un p\u00fablico diferente. Al igual que se hace con los museos cada a\u00f1o, el Gobierno de la Provincia de Buenos Aires anunci\u00f3 que este viernes 4&#8230;<\/p>\n","protected":false},"author":4,"featured_media":4951,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,35],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/4950"}],"collection":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/comments?post=4950"}],"version-history":[{"count":1,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/4950\/revisions"}],"predecessor-version":[{"id":4952,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/4950\/revisions\/4952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media\/4951"}],"wp:attachment":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media?parent=4950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/categories?post=4950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/tags?post=4950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}