{"id":4996,"date":"2022-02-21T11:04:00","date_gmt":"2022-02-21T14:04:00","guid":{"rendered":"https:\/\/www.cuatrogiros.com\/4G\/?p=4996"},"modified":"2022-02-14T16:22:36","modified_gmt":"2022-02-14T19:22:36","slug":"la-salud-visual-en-epoca-de-pantallas","status":"publish","type":"post","link":"https:\/\/www.cuatrogiros.com\/4G\/la-salud-visual-en-epoca-de-pantallas\/","title":{"rendered":"La salud visual en \u00e9poca de pantallas"},"content":{"rendered":"\n<p><em>Una problem\u00e1tica que afecta a grandes y chicos, pero que los m\u00e1s peque\u00f1os incrementan su exposici\u00f3n a las pantallas producto del comienzo de las clases y el inicio de las actividades que requiere el uso de computadoras. \u00bfC\u00f3mo se pueden prevenir los problemas que las pantallas generan en nuestra vista?<\/em><br><br>Seg\u00fan las recomendaciones, los ni\u00f1os de 0 a 2 a\u00f1os, no deben estar expuestos a pantallas, de 2 a 5 a\u00f1os, entre media y una hora al d\u00eda; 7 a 12 a\u00f1os una hora al d\u00eda; de 12 a 15 a\u00f1os, una hora y media y mayores de 16 a\u00f1os dos horas al d\u00eda. Pero lejos de eso estamos hoy d\u00eda con la enorme exposici\u00f3n continua que los m\u00e1s chicos tienen.<\/p>\n\n\n\n<p>\u00abYa se ven\u00eda estudiando por el aumento de pantallas y el cambio a la luz led, lo cual genera una gran irritaci\u00f3n y se viene buscando reducir la radiaci\u00f3n que provoca en la vista. El crecimiento de problemas en la visi\u00f3n es estrictamente proporcional al crecimiento del uso de pantallas. No distingue edades, durante la pandemia el sentido m\u00e1s exigido fue la vista y  hoy convivimos ya con esa exposici\u00f3n\u00bb asegura Alejandro Giunta de Optical Net.<\/p>\n\n\n\n<p>Es que a pesar de que estemos retomando cierta normalidad despu\u00e9s de la pandemia, el acostumbramiento a lo digital y lo virtual durante los per\u00edodos de aislamiento parece haber llegado para quedarse e incluso, cada vez m\u00e1s colegios incluyen la tecnolog\u00eda en el dictado de clases y con ello, la exposici\u00f3n de los m\u00e1s chicos a las pantallas.<\/p>\n\n\n\n<p>\u00abLas afecciones que m\u00e1s se pueden observar son enrojecimiento del ojo, malestar continuo, incluso hay problemas con el sue\u00f1o por pasar mucho tiempo con pantallas. Es un tema mucho m\u00e1s m\u00e9dico, pero existen investigaciones que ya hablan de la Tensi\u00f3n Visual Digital, producto de la exposici\u00f3n\u00bb agrega Alejandro Giunta.<\/p>\n\n\n\n<p>Hoy d\u00eda, le cont\u00f3 Giunta de Optical Net a Cuatro Giros, ya hay oftalmopediatras que recetan lentes sin aumento, o \u00abanteojos neutros\u00bb, lo cual reduce el impacto de la luz azul al poner un cristal que impide su ingreso al ojo. \u00abNo era frecuente el uso de este tipo de anteojos, sino que se dio por el crecimiento precipitado durante la pandemia porque gener\u00f3 una congesti\u00f3n visual. A tal punto fue, que durante ese per\u00edodo hubo falta de material para los anteojos producto de la demanda\u00bb<\/p>\n\n\n\n<p>\u00abEl Blue blocker son cristales que, ademas de filtro UV y antireflex, permite el bloqueo de la luz azul violeta, que es la que afecta al ojo, no as\u00ed la luz azul turquesa que es la m\u00e1s saludable a la vista\u00bb nos cont\u00f3 Alejandro.<\/p>\n\n\n\n<p>\u00abAdem\u00e1s de buscar material de calidad para mayor protecci\u00f3n, la recomendaci\u00f3n es visitar al oftalm\u00f3logo para control y que sea el profesional quien recete los anteojos con la graduaci\u00f3n necesaria. En caso de no tener ning\u00fan inconveniente, se puede hacer los anteojos neutros para mayor prevenci\u00f3n. En ni\u00f1os, se recomienda una visita anual y en mayores de cuarenta a\u00f1os, al a\u00f1o o a\u00f1o y medio. Igual esto depender\u00e1 tambi\u00e9n de la problem\u00e1tica que cada uno pueda tener\u00bb finaliz\u00f3 Alejandro Giunda de Optical Net.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una problem\u00e1tica que afecta a grandes y chicos, pero que los m\u00e1s peque\u00f1os incrementan su exposici\u00f3n a las pantallas producto del comienzo de las clases y el inicio de las actividades que requiere el uso de computadoras. \u00bfC\u00f3mo se pueden prevenir los problemas que las&#8230;<\/p>\n","protected":false},"author":4,"featured_media":4997,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,187,38],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/4996"}],"collection":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/comments?post=4996"}],"version-history":[{"count":1,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/4996\/revisions"}],"predecessor-version":[{"id":4998,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/4996\/revisions\/4998"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media\/4997"}],"wp:attachment":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media?parent=4996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/categories?post=4996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/tags?post=4996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}