{"id":5007,"date":"2022-02-24T16:59:47","date_gmt":"2022-02-24T19:59:47","guid":{"rendered":"https:\/\/www.cuatrogiros.com\/4G\/?p=5007"},"modified":"2022-02-24T16:59:50","modified_gmt":"2022-02-24T19:59:50","slug":"5-claves-para-entender-la-guerra-rusia-ucrania","status":"publish","type":"post","link":"https:\/\/www.cuatrogiros.com\/4G\/5-claves-para-entender-la-guerra-rusia-ucrania\/","title":{"rendered":"5 claves para entender la guerra Rusia &#8211; Ucrania"},"content":{"rendered":"\n<p><em>Tras varios d\u00edas de tensi\u00f3n, el conflicto finalmente alcanz\u00f3 su punto m\u00e1s \u00e1lgido y Rusia invadi\u00f3 Ucrania, dando inicio a una guerra que tiene al mundo en vilo. Ahora, \u00bfpor qu\u00e9 se da origen a este conflicto? en Cuatro Giros te contamos lo que ten\u00e9s que saber para entender lo que ocurre en tierras europeas.<\/em><\/p>\n\n\n\n<p>La Organizaci\u00f3n del Tratado del Atl\u00e1ntico Norte, que es una alianza militar intergubernamental, la cual se rige por el Tratado del Atl\u00e1ntico Norte, se encuentra realizando un proceso de expansi\u00f3n en Europa del Este. Para ello, invit\u00f3 a sumarse a Ucrania, ex URSS, y Georgia, lo cual preocupa a Rusia en relaci\u00f3n al dominio geopol\u00edtico.<\/p>\n\n\n\n<p>Frente a esto, Rusia envi\u00f3 casi 100 mil fuerzas a la frontera que limita con Ucrania y comenz\u00f3 a realizar pruebas militares. Dos regiones de Ucrania se proclamaron independientes con el apoyo del gobierno ruso: la Rep\u00fablica Popular de Donetsk (RPD) y la Rep\u00fablica Popular de Lugansk (RPL).<\/p>\n\n\n\n<p>Frente a los movimientos de las fuerzas rusas en la frontera, Estados Unidos y los pa\u00edses de la OTAN impusieron sanciones econ\u00f3micas a Rusia que tensionaron el conflicto y terminaron de ser el \u00faltimo eslab\u00f3n de una cadena que llev\u00f3 al inicio del conflicto b\u00e9lico.<\/p>\n\n\n\n<p>Anteriormente Ucrania pertenec\u00eda a la Uni\u00f3n de Rep\u00fablicas Socialistas Sovi\u00e9ticas, hasta que en agosto de 1991, tras la disoluci\u00f3n de la URSS, logr\u00f3 su independencia.<\/p>\n\n\n\n<p>Ayer el Consejo de Seguridad de Ucrania aprob\u00f3 el estado de Emergencia, y durante la noche Rusia comenz\u00f3 con ataques en los alrededores de Kiev.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras varios d\u00edas de tensi\u00f3n, el conflicto finalmente alcanz\u00f3 su punto m\u00e1s \u00e1lgido y Rusia invadi\u00f3 Ucrania, dando inicio a una guerra que tiene al mundo en vilo. Ahora, \u00bfpor qu\u00e9 se da origen a este conflicto? en Cuatro Giros te contamos lo que ten\u00e9s&#8230;<\/p>\n","protected":false},"author":4,"featured_media":5008,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,14],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/5007"}],"collection":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/comments?post=5007"}],"version-history":[{"count":1,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/5007\/revisions"}],"predecessor-version":[{"id":5009,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/5007\/revisions\/5009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media\/5008"}],"wp:attachment":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media?parent=5007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/categories?post=5007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/tags?post=5007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}