{"id":5020,"date":"2022-03-04T14:05:49","date_gmt":"2022-03-04T17:05:49","guid":{"rendered":"https:\/\/www.cuatrogiros.com\/4G\/?p=5020"},"modified":"2022-03-04T14:05:50","modified_gmt":"2022-03-04T17:05:50","slug":"mujeres-empoderadas-a-traves-del-deporte","status":"publish","type":"post","link":"https:\/\/www.cuatrogiros.com\/4G\/mujeres-empoderadas-a-traves-del-deporte\/","title":{"rendered":"Mujeres empoderadas a trav\u00e9s del deporte"},"content":{"rendered":"\n<p><em>Crear&nbsp;espacios f\u00edsicos y emocionalmente seguros para la pr\u00e1ctica&nbsp;deportiva&nbsp;con el&nbsp;fin&nbsp;de&nbsp;fortalecer&nbsp;el liderazgo,la&nbsp;autoestima, la salud,el empoderamiento econ\u00f3mico&nbsp;y&nbsp;la prevenci\u00f3n de la violencia de g\u00e9nero. Esto es lo que propone la iniciativa de ONU Mujeres y el Comit\u00e9 Ol\u00edmpico Internacional que&nbsp;impuls\u00f3 el&nbsp;empoderamientoen&nbsp;chicas de barrios populares de la Ciudad Aut\u00f3noma de Buenos Aires.&nbsp;<\/em><\/p>\n\n\n\n<p>\u201cCon el deporte yo aprend\u00ed a sonre\u00edr\u201d. \u201cYo aprend\u00ed lo que es trabajar en equipo\u201d. \u201cAprend\u00ed a levantarme\u201d. \u201cYo aprend\u00ed a expresar mis sentimientos\u201d. \u201cAprend\u00ed a que me escuchen\u201d. Las voces de las chicas crecen y se multiplican, al igual que&nbsp;sus oportunidades y el acceso a derechos.&nbsp;<em>&nbsp;<\/em><\/p>\n\n\n\n<p>Todas&nbsp;viven en&nbsp;barrios populares de la Ciudad Aut\u00f3noma de Buenos Aires y&nbsp;participaron&nbsp;del programa&nbsp;Una Victoria Lleva a la Otra (UVLO),&nbsp;una iniciativa conjunta de ONU Mujeres y el Comit\u00e9 Ol\u00edmpico Internacional, que surgi\u00f3 en Brasil como un legado social de los Juegos Ol\u00edmpicos R\u00edo 2016 y en el caso de Argentina, de los Juegos Ol\u00edmpicos de la Juventud (Buenos Aires, 2018).&nbsp;<\/p>\n\n\n\n<p>En la transici\u00f3n a la adolescencia, ellas reciben menos incentivos que sus compa\u00f1eros para desarrollar habilidades&nbsp;deportivas,cuentan con&nbsp;menor autonom\u00eda sobre sus cuerpos y enfrentan la responsabilidad de proteger su salud sexual y reproductiva.&nbsp;En respuesta a estas desigualdades,UVLO&nbsp;ha&nbsp;logrado&nbsp;mejorar la&nbsp;autoconfianza&nbsp;y&nbsp;conocimientos sobre salud, derechos, empoderamiento econ\u00f3mico y planificaci\u00f3n financiera&nbsp;de&nbsp;chicas que antes&nbsp;no&nbsp;tuvieron acceso a este tipo de informaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p>\u201cNuestro objetivo es empoderar a ni\u00f1as y adolescentes en sus habilidades socioemocionales, capacidades de autonom\u00eda y conocimiento de sus derechos, utilizando el deporte con perspectiva de g\u00e9nero como una herramienta para la transformaci\u00f3n&nbsp;social. De esta manera apuntamos a construir un futuro mejor para ellas y generar un impacto positivo en sus familias y comunidades\u201d,&nbsp;se\u00f1ala&nbsp;Lisa Solmirano, coordinadora de&nbsp;Una Victoria Lleva a la Otra&nbsp;en Argentina.&nbsp;<\/p>\n\n\n\n<p>Luego de una primera fase de implementaci\u00f3n exitosa,&nbsp;actualmente&nbsp;UVLO concentra sus esfuerzos en difundir la metodolog\u00eda y sensibilizar&nbsp;a&nbsp;las&nbsp;empresas,&nbsp;el&nbsp;sector privado&nbsp;y p\u00fablico sobre el potencial de este tipo de abordajes para alcanzar objetivos de&nbsp;igualdad de&nbsp;g\u00e9nero, a trav\u00e9s de seminarios y talleres de trabajo.&nbsp;<\/p>\n\n\n\n<p>Durante 2021, la iniciativa&nbsp;se puso en pr\u00e1ctica&nbsp;en la Ciudad de Buenos Airescon el&nbsp;apoyo deWomenWin&nbsp;y en conjunto con la&nbsp;Fundaci\u00f3n para el Estudio e Investigaci\u00f3n de la Mujer (FEIM), Fundaci\u00f3n SES &#8211; Sostenibilidad, Educaci\u00f3n, Solidaridad, y el Ministerio de Desarrollo Humano y H\u00e1bitat del Gobierno de la Ciudad de Buenos Aires,&nbsp;adem\u00e1s de&nbsp;distintas organizaciones comunitarias.Se realizaron talleres y pr\u00e1cticas deportivas para contribuir a la formaci\u00f3n integral de las&nbsp;j\u00f3venes&nbsp;en&nbsp;cuatro ejes tem\u00e1ticos: liderazgo y autoestima; salud y derechos sexuales y reproductivos; derechos y eliminaci\u00f3n de la violencia contra las&nbsp;mujeres y ni\u00f1as; objetivos y planificaci\u00f3n profesional y financiera.&nbsp;<\/p>\n\n\n\n<p>\u201cEl mayor logro del programa es poder registrar que existe una otra, que hay alguien que est\u00e1 viviendo cosas parecidas a las m\u00edas y que juntas somos m\u00e1s poderosas\u201d,&nbsp;afirma&nbsp;Eugenia, entrenadora del programa.&nbsp;<\/p>\n\n\n\n<p>\u201cEl deporte es una herramienta para la vida, las pibas se empoderan en la cancha, son protagonistas de su propio juego\u201d,&nbsp;agrega&nbsp;Noelia, entrenadora&nbsp;del programa.&nbsp;<\/p>\n\n\n\n<p><strong>Desafiando estereotipos y roles&nbsp;de g\u00e9nero&nbsp;asignados&nbsp;<\/strong><\/p>\n\n\n\n<p>El deporte,adem\u00e1s de promover&nbsp;la salud f\u00edsica y mental, es una poderosa herramienta para derribar los estereotipos y roles de g\u00e9nero que generan discriminaci\u00f3n, violencias y desigualdades.&nbsp;<\/p>\n\n\n\n<p>\u201cLa iniciativa se enfoca fundamentalmente en&nbsp;chicas&nbsp;adolescentes porque es una etapa de la vida donde dejan de practicar deportes por dificultades de acceso, falta de espacios seguros, acoso, violencias y estereotipos nocivos que afectan su participaci\u00f3n y su inclusi\u00f3n\u201d,&nbsp;explicaSolmirano.&nbsp;<\/p>\n\n\n\n<p><strong>Los n\u00fameros de Una Victoria Lleva a la Otra en Argentina&nbsp;<\/strong><\/p>\n\n\n\n<p>1.236&nbsp;participantes&nbsp;adolescentes&nbsp;<\/p>\n\n\n\n<p>128&nbsp;entrenadoras y facilitadoras capacitadas&nbsp;<\/p>\n\n\n\n<p>46&nbsp;organizaciones deportivas comunitarias implementando actividades&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>Datos:&nbsp;Barreras y desigualdades&nbsp;de ni\u00f1as y adolescentes en el deporte&nbsp;&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>En el mundo<\/strong>&nbsp;<\/p>\n\n\n\n<p>&#8211;&nbsp;Las ni\u00f1as dedican un 40% m\u00e1s de tiempo&nbsp;a&nbsp;las tareas de cuidado que los ni\u00f1os.&nbsp;A m\u00e1s tareas del hogar menos tiempo para jugar, aprender y practicar deportes&nbsp;(UNICEF, 2016).&nbsp;<\/p>\n\n\n\n<p>&#8211;&nbsp;La desigualdad crece a medida que las ni\u00f1as se hacen mayores, ya que cuando cumplen entre 10 y 14 a\u00f1os dedican un 50% m\u00e1s&nbsp;de tiempo&nbsp;a las tareas de cuidado&nbsp;(UNICEF, 2016).&nbsp;<\/p>\n\n\n\n<p><strong>En Argentina<\/strong>&nbsp;<\/p>\n\n\n\n<p>&#8211;&nbsp;El 60% de los adolescentes de 13 a 17 a\u00f1os no realizan ninguna actividad f\u00edsica o deportiva extraescolar. De ese porcentaje, las mujeres&nbsp;realizan un 20% menos deporte (Observatorio Social del Deporte, 2021).&nbsp;<\/p>\n\n\n\n<p>&#8211;&nbsp;De los adolescentes que no realizan ninguna actividad f\u00edsica extraescolar, el 74,2% pertenecen al nivel socioecon\u00f3mico m\u00e1s bajo y el 71,7% vive en villas o asentamientos&nbsp;(Observatorio Social del Deporte, 2021).&nbsp;<\/p>\n\n\n\n<p>Adem\u00e1s,&nbsp;de acuerdo con un relevamiento realizado por la Unidad Fiscal Especializada en Violencia contra las Mujeres (UFEM, 2019):&nbsp;<\/p>\n\n\n\n<p>&#8211;&nbsp;Cerca del 90% de las v\u00edctimas de violencia sexual son mujeres.&nbsp;<\/p>\n\n\n\n<p>&#8211;&nbsp;Casi el 40% de las v\u00edctimas son menores de 18 a\u00f1os.&nbsp;<\/p>\n\n\n\n<p><strong>Acerca del programa&nbsp;<\/strong><\/p>\n\n\n\n<p>Una Victoria Lleva a la Otra&nbsp;es una iniciativa conjunta de ONU Mujeres y el Comit\u00e9 Ol\u00edmpico Internacional&nbsp;quedurante su primera fase en 2021 empoder\u00f3 a m\u00e1s de 1.200 ni\u00f1as y adolescentes de barrios populares de la Ciudad Aut\u00f3noma de Buenos Aires (Argentina)&nbsp;en sus habilidades, capacidades de autonom\u00eda y conocimiento de sus derechos a trav\u00e9s del acceso al deporte en espacios seguros.&nbsp;<\/p>\n\n\n\n<p>Junto a distintas organizaciones comunitarias&nbsp;el programa desarroll\u00f3&nbsp;talleres tem\u00e1ticos y pr\u00e1cticas&nbsp;deportivas&nbsp;dirigidas a&nbsp;las participantes&nbsp;con el objetivo de poner fin a&nbsp;las desigualdades&nbsp;y&nbsp;los&nbsp;estereotipos de g\u00e9nero&nbsp;e impulsar un desarrollo pleno en la adolescencia y una vida libre de discriminaciones y violencia.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>M\u00e1s informaci\u00f3n:<a href=\"http:\/\/link.virtualmailer.com.ar\/02d4fe1347461bdcd44061a386927323\/6b007ef2f58592ba4099a134b1b189ce\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/unavictoriallevaalaotra.org.ar\/<\/a>&nbsp;<\/p>\n\n\n\n<p>Video Institucional:&nbsp;<a href=\"http:\/\/link.virtualmailer.com.ar\/5832ee528179d722b017abeff335802a\/6b007ef2f58592ba4099a134b1b189ce\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/bit.ly\/3pcpsVB<\/a>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Crear&nbsp;espacios f\u00edsicos y emocionalmente seguros para la pr\u00e1ctica&nbsp;deportiva&nbsp;con el&nbsp;fin&nbsp;de&nbsp;fortalecer&nbsp;el liderazgo,la&nbsp;autoestima, la salud,el empoderamiento econ\u00f3mico&nbsp;y&nbsp;la prevenci\u00f3n de la violencia de g\u00e9nero. Esto es lo que propone la iniciativa de ONU Mujeres y el Comit\u00e9 Ol\u00edmpico Internacional que&nbsp;impuls\u00f3 el&nbsp;empoderamientoen&nbsp;chicas de barrios populares de la Ciudad Aut\u00f3noma de&#8230;<\/p>\n","protected":false},"author":4,"featured_media":5021,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,64],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/5020"}],"collection":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/comments?post=5020"}],"version-history":[{"count":1,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/5020\/revisions"}],"predecessor-version":[{"id":5022,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/5020\/revisions\/5022"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media\/5021"}],"wp:attachment":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media?parent=5020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/categories?post=5020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/tags?post=5020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}