{"id":5726,"date":"2022-12-15T15:36:38","date_gmt":"2022-12-15T18:36:38","guid":{"rendered":"https:\/\/www.cuatrogiros.com\/4G\/?p=5726"},"modified":"2022-12-28T11:58:58","modified_gmt":"2022-12-28T14:58:58","slug":"como-ahorrar-dinero-en-las-compras-de-productos-tecnologicos-2","status":"publish","type":"post","link":"https:\/\/www.cuatrogiros.com\/4G\/como-ahorrar-dinero-en-las-compras-de-productos-tecnologicos-2\/","title":{"rendered":"C\u00f3mo ahorrar dinero en las compras de productos tecnol\u00f3gicos"},"content":{"rendered":"<p><em>Todos podemos cuidar el bolsillo y el planeta si optamos por comprar productos reacondicionados. Recuperando y reacondicionando los equipos en desuso, se logra extender la vida \u00fatil de los aparatos electr\u00f3nicos a la vez que se cuida el medio ambiente.<\/em><\/p>\n<p>El Refurbished es LA alternativa efectiva en la reutilizaci\u00f3n de aparatos electr\u00f3nicos y se perfila como pieza clave en la implementaci\u00f3n de la Econom\u00eda Circular.<\/p>\n<p>Si bien a trav\u00e9s de la tecnolog\u00eda nuestras actividades diarias son mucho m\u00e1s sencillas y r\u00e1pidas, aprovechando todos nuestros recursos de una forma inteligente podemos ser m\u00e1s eficientes.<\/p>\n<p>En los tiempos en los que vivimos tenemos la necesidad de disponer de nuestro presupuesto de la manera m\u00e1s conveniente posible, optimizando las compras para lograr el tan deseado ahorro de dinero.<\/p>\n<p>El comprador tecnol\u00f3gico de hoy tiene m\u00e1s conciencia del impacto de sus acciones a nivel econ\u00f3mico y tambi\u00e9n a nivel ambiental. As\u00ed lo demuestran estudios recientes que evidencian desde 2020 un aumento en nuestro pa\u00eds en el consumo de productos sustentables, dado que el usuario empieza a valorar c\u00f3mo reciclar y reutilizar ayuda en el cuidado de nuestro entorno.<\/p>\n<p>Por este motivo, los aparatos electr\u00f3nicos reacondicionados son una gran alternativa, no s\u00f3lo por el ahorro de dinero sino tambi\u00e9n por la posibilidad de cuidar el medioambiente.<\/p>\n<p>Las 5 R&#8217;s ecol\u00f3gicas: Reducir, Reciclar, Reutilizar, Reparar y Recuperar<\/p>\n<p>Mediante el refurbished se recuperan los equipos inform\u00e1ticos, evitando as\u00ed la generaci\u00f3n de residuos electr\u00f3nicos a la vez que se da una segunda vida a los productos reutilizables.<\/p>\n<p>Por consiguiente, la reutilizaci\u00f3n es la alternativa m\u00e1s indicada para recuperar los productos tecnol\u00f3gicos, de una manera econ\u00f3mica, t\u00e9cnica y ambientalmente m\u00e1s eficiente que el reciclaje. Su implementaci\u00f3n debe realizarse de una manera acorde, a trav\u00e9s de procesos seguros, certificados y auditables.<\/p>\n<p>Esta nueva forma de invertir en tecnolog\u00eda amigable con el medio ambiente demuestra que tanto consumidores como empresas pueden contribuir a lograr una sociedad m\u00e1s sostenible de varias maneras.<\/p>\n<p>Una tendencia que est\u00e1 cobrando gran impulso<\/p>\n<p>En este contexto, cada vez son m\u00e1s los argentinos que, impulsados por el aumento en los precios de los equipos nuevos, se animan a elegir productos refurbished.<\/p>\n<p>Dadas las circunstancias, los especialistas de Pc Discount se\u00f1alan que \u201ccomprar tecnolog\u00eda de calidad no significa pagar m\u00e1s\u201d, aclarando que la mejor manera de obtener un producto de mejor calidad a un precio conveniente es \u201cevaluar el producto que tenga la mejor relaci\u00f3n calidad-precio\u201d.<\/p>\n<p>Qu\u00e9 es un producto \u201crefurbished\u201d<\/p>\n<p>A trav\u00e9s del proceso de refurbished, los equipos inform\u00e1ticos provenientes del recambio tecnol\u00f3gico de las empresas y que tienen valor comercial, son revisados, reparados y re-embalados para luego pasar a la re-comercializaci\u00f3n. El procedimiento consta de un exhaustivo Proceso de Verificaci\u00f3n T\u00e9cnica de 11 pasos para asegurar su funcionamiento.<\/p>\n<p>Por el contrario, aquellas partes que no, se reciclan y se realiza la<\/p>\n<p>destrucci\u00f3n de la informaci\u00f3n y el borrado de los discos bajo est\u00e1ndares internacionales (NIST SP 800-88), evitando as\u00ed posibles fugas de datos sensibles; y de acuerdo a normas ambientales, en una Planta de Reciclaje Oficial que emite el certificado correspondiente.<\/p>\n<p>Por consiguiente, a trav\u00e9s de este proceso, le da un valor residual y extiende el ciclo de vida de gran parte del parque de los equipos que desconectan, lo que significa un importante ahorro para las empresas en la compra de los equipos nuevos a la vez que recuperan el valor de los equipos en desuso. De esta manera se cierra perfectamente el proceso inverso del ciclo de vida del hardware (tambi\u00e9n llamado Activos IT).<\/p>\n<p>&nbsp;<\/p>\n<p>Para aquellos consumidores indecisos los especialistas de Pc Discount enumeran 5 razones para comprar productos reacondicionados:<\/p>\n<p>1-Precio:<br \/>\nLos productos reacondicionados tienen un precio mucho m\u00e1s bajo en comparaci\u00f3n con uno nuevo (no sobrepasan el 50% del valor).<\/p>\n<p>2-Calidad:<br \/>\nLos productos reacondicionados ofrecen excelentes prestaciones al igual que uno nuevo de similares caracter\u00edsticas.<br \/>\nSe trabaja con productos de gama empresarial (Dell, Lenovo, HP y Apple) que, dadas sus caracter\u00edsticas, son aptos para soportar un nuevo ciclo de uso y se producen en funci\u00f3n de los requerimientos de las grandes empresas, que a diferencia de la l\u00ednea hogare\u00f1a, cuentan con una construcci\u00f3n muy robusta, m\u00e1s orientada al uso intensivo, tienen mayor durabilidad en el tiempo y est\u00e1n elaborados con materiales de gran calidad.<\/p>\n<p>Por ejemplo, las notebooks poseen un subchasis que las hace inmunes al tecleo constante y en algunos casos con sistemas antiderrame de l\u00edquidos. Hay modelos que est\u00e1n hechos de aleaci\u00f3n de carbono o aluminio en sus carcasas.<\/p>\n<p>Adem\u00e1s, al comprar un equipo de marca reconocida es m\u00e1s f\u00e1cil conseguir repuestos originales o alternativas seleccionadas.<\/p>\n<p>Otra ventaja de los productos reacondicionados es que ofrecen la posibilidad de mejorar sus configuraciones ampliando memoria RAM o agregando o cambiando discos r\u00edgidos por SSD o M2, que son de las \u00faltimas tecnolog\u00edas.<\/p>\n<p>3-Cuidado del medio ambiente:<br \/>\nMediante la recuperaci\u00f3n sustentable, se reutiliza el 94% de los equipos en desuso, evitando as\u00ed la generaci\u00f3n de residuos electr\u00f3nicos a la vez que se da una segunda vida a los productos reutilizables.<br \/>\nDe esta manera se disminuye la extracci\u00f3n de materias primas, cuidando los recursos naturales a la vez que se reduce la contaminaci\u00f3n del aire, el agua y el suelo, contribuyendo al cuidado de la salud de los seres vivos.<\/p>\n<p>En materia econ\u00f3mica, representan puestos de trabajo necesarios para realizar la separaci\u00f3n y clasificaci\u00f3n correspondiente de los diferentes materiales.<\/p>\n<p>4-Garant\u00eda<br \/>\nOtra enorme ventaja de estos equipos es la posibilidad de conseguir repuestos de todo tipo, lo cual alarga su vida \u00fatil casi indefinidamente.<br \/>\nLos productos reacondicionados tienen Garant\u00eda Propia Certificada de 12 meses emitida por Pc Discount que cubre cualquier falla de hardware. (No se garantizan consumibles como bater\u00edas, cartuchos, toners o cabezales).<\/p>\n<p>5-Proveedor<br \/>\nLa elecci\u00f3n del lugar de compra es un punto fundamental. Es necesario que el proveedor o retailer tenga una buena trayectoria en el mercado y brinde asesor\u00eda a sus clientes. Asimismo, debe contar con variedad de opciones junto a una garant\u00eda adecuada, con el respaldo de stock de repuestos y de equipos.<\/p>\n<p>En definitiva, el Refurbished est\u00e1 teniendo cada vez m\u00e1s aceptaci\u00f3n en el mercado debido a que un equipo recuperado sin costo de materia prima genera una alta rentabilidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todos podemos cuidar el bolsillo y el planeta si optamos por comprar productos reacondicionados. Recuperando y reacondicionando los equipos en desuso, se logra extender la vida \u00fatil de los aparatos electr\u00f3nicos a la vez que se cuida el medio ambiente. El Refurbished es LA alternativa&#8230;<\/p>\n","protected":false},"author":4,"featured_media":5727,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/5726"}],"collection":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/comments?post=5726"}],"version-history":[{"count":1,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/5726\/revisions"}],"predecessor-version":[{"id":5728,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/5726\/revisions\/5728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media\/5727"}],"wp:attachment":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media?parent=5726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/categories?post=5726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/tags?post=5726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}