{"id":6315,"date":"2023-05-03T10:54:45","date_gmt":"2023-05-03T13:54:45","guid":{"rendered":"https:\/\/www.cuatrogiros.com\/4G\/?p=6315"},"modified":"2023-05-03T11:26:40","modified_gmt":"2023-05-03T14:26:40","slug":"winnie-the-pooh-y-el-regimen-chino","status":"publish","type":"post","link":"https:\/\/www.cuatrogiros.com\/4G\/winnie-the-pooh-y-el-regimen-chino\/","title":{"rendered":"El oso de la discordia en\u00a0China"},"content":{"rendered":"<div><i>Qu\u00e9 relaci\u00f3n hay entre el amigable osito y las cr\u00edticas hacia Xi Jinping y su particular mandato en el pa\u00eds asi\u00e1tico. Lo declararon\u00a0\u201cursus-non-gratus\u00bb, y ha nacido un meme.<\/i><\/div>\n<div><\/div>\n<div>Winnie the Pooh es un oso bonach\u00f3n y cr\u00e9dulo. Eso lo convierte en un protagonista improbable para una pel\u00edcula de terror. \u201cWinnie the Pooh: Sangre y miel\u201d, estrenada a principios de a\u00f1o, ha sido criticada por los espectadores de todo el mundo. En Hong Kong fue retirada de los cines antes de su estreno. Ni siquiera lleg\u00f3 tan lejos en China continental. Esto no se debe a la cantidad poco convincente de escenas sangrientas, ni a que la premisa de la pel\u00edcula sea absurda. Cualquier representaci\u00f3n de Pooh atraer\u00e1 la atenci\u00f3n de las autoridades chinas. \u00bfPor qu\u00e9?<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>Cuando Xi Jinping visit\u00f3 a Barack Obama en la Casa Blanca en 2013, un usuario de las redes sociales coment\u00f3 que la pareja se parec\u00eda a Pooh y Tigger, el amigo ficticio del oso. El presidente estadounidense era alto y \u00e1gil; el l\u00edder chino, en comparaci\u00f3n, parec\u00eda achaparrado y un poco barrig\u00f3n. El enjuto cuerpo de Obama mide 1,87 metros. La estatura de Xi, aunque es un misterio, se cree que oscila entre 1,75 y 1,78 metros. Sea cual sea la verdad, ha nacido un meme.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>La censura de Internet en China es un juego de topo. Las cr\u00edticas directas al Partido Comunista y a su Secretario General son r\u00e1pidamente reprimidas, por lo que los internautas deben encontrar formas ingeniosas de quejarse o burlarse antes de que las autoridades las descubran. Durante un tiempo, un inofensivo oso se convirti\u00f3 en ese escurridizo topo. Se sab\u00eda que las menciones de Pooh en Internet eran referencias al l\u00edder chino.<\/div>\n<div><\/div>\n<div>En 2015, una imagen de Xi asom\u00e1ndose por el techo solar de una limusina durante un desfile militar fue ampliamente comparada con una de Pooh sentado en un coche de juguete. Se convirti\u00f3 en la imagen m\u00e1s censurada del a\u00f1o en China, seg\u00fan Global Risks Insights, una organizaci\u00f3n que analiza el riesgo pol\u00edtico. En 2017 \u5c0f\u718a\u7ef4\u5c3c, los caracteres chinos de Winnie-the-Pooh (literalmente \u201cOsito Winnie\u201d) hab\u00edan sido efectivamente prohibidos en Internet en China.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>Dado que la comparaci\u00f3n con Xi era a menudo desenfadada, la reacci\u00f3n puede parecer un exceso de sensibilidad. Al fin y al cabo, los l\u00edderes mundiales intentan a menudo camuflar su autoritarismo con un alter ego entra\u00f1able: El propio Xi se regocijaba con el apodo de \u201cXi Dada\u201d, utilizado con adulaci\u00f3n por los medios de comunicaci\u00f3n estatales, hasta que algunos empezaron a burlarse de \u00e9l por ello. Pero el l\u00edder chino sufre de un rasgo m\u00e1s com\u00fan entre los autoritarios: una piel fina.<\/div>\n<div><\/div>\n<div>Xi ha acumulado m\u00e1s poder que cualquiera de sus predecesores desde Mao Zedong. Al igual que Mao, ha forjado un culto a la personalidad en el que se le considera infalible. Est\u00e1 obsesionado con la imagen. Se espera que los cuadros del Partido aprendan de memoria la sabidur\u00eda de Xi. No hay lugar para las burlas, por suaves que sean.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>Por eso, China env\u00eda ej\u00e9rcitos de censores y polic\u00edas secretos a rastrear los mensajes en l\u00ednea. Las empresas de Internet emplean a decenas de miles de moderadores que detectan y eliminan en cuesti\u00f3n de segundos ideas e im\u00e1genes prohibidas, incluidas las de simp\u00e1ticos animales. La sensibilidad de los censores puede rayar en lo rid\u00edculo.<\/div>\n<div><\/div>\n<div>El a\u00f1o pasado, un hombre retransmiti\u00f3 en directo c\u00f3mo se com\u00eda una tarta. A las autoridades les preocup\u00f3 que el manjar se pareciera a un tanque, as\u00ed que lo sacaron del aire por miedo a que aludiera a los que expulsaron a los manifestantes estudiantiles de la plaza de Tiananmen con fuerza asesina en 1989. El a\u00f1o pasado, la Administraci\u00f3n del Ciberespacio de China promulg\u00f3 una norma seg\u00fan la cual todos los comentarios en los sitios de noticias chinos deben ser examinados antes de ser publicados.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>En el a\u00f1o 2000, Bill Clinton predijo que el r\u00e9gimen autoritario de China, decidido a vigilar lo que la gente dice de \u00e9l, se mostrar\u00eda impotente en la era de los tel\u00e9fonos inteligentes y la libre circulaci\u00f3n de informaci\u00f3n en l\u00ednea. De hecho, el gobierno de Xi -dejando a un lado a algunos osos pillos- ha demostrado ser m\u00e1s que capaz de mantener el control.<\/div>\n<div><\/div>\n<div>Como dec\u00eda A.A. Milne (conocido de Winnie the Pooh, por cierto): \u201cLa organizaci\u00f3n es lo que haces antes de hacer algo para que, cuando lo hagas, no est\u00e9 todo mezclado\u201d.<br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/><i>Fuente: \u00a9 2022, The Economist Newspaper Limited. All rights reserved.<\/i><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Qu\u00e9 relaci\u00f3n hay entre el amigable osito y las cr\u00edticas hacia Xi Jinping y su particular mandato en el pa\u00eds asi\u00e1tico. Lo declararon\u00a0\u201cursus-non-gratus\u00bb, y ha nacido un meme. Winnie the Pooh es un oso bonach\u00f3n y cr\u00e9dulo. Eso lo convierte en un protagonista improbable para&#8230;<\/p>\n","protected":false},"author":6,"featured_media":6316,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50,6,14],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/6315"}],"collection":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/comments?post=6315"}],"version-history":[{"count":2,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/6315\/revisions"}],"predecessor-version":[{"id":6329,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/6315\/revisions\/6329"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media\/6316"}],"wp:attachment":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media?parent=6315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/categories?post=6315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/tags?post=6315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}