{"id":6333,"date":"2023-05-09T11:42:36","date_gmt":"2023-05-09T14:42:36","guid":{"rendered":"https:\/\/www.cuatrogiros.com\/4G\/?p=6333"},"modified":"2024-04-17T21:35:29","modified_gmt":"2024-04-18T00:35:29","slug":"los-dos-polos-de-la-grieta-fracasaron","status":"publish","type":"post","link":"https:\/\/www.cuatrogiros.com\/4G\/los-dos-polos-de-la-grieta-fracasaron\/","title":{"rendered":"\u201cLos dos polos de la grieta fracasaron\u201d"},"content":{"rendered":"<p><em>El ex gobernador de Salta vuelve a ser parte de un armado electoral que pretende salir de la polarizaci\u00f3n del Frente de Todos y de Juntos por el Cambio, al igual que en 2019 cuando acompa\u00f1\u00f3 a Lavagna en la f\u00f3rmula presidencial. Fue dur\u00edsimo contra la actual gesti\u00f3n: \u00abComo peronista lo del kirchnerismo me da verg\u00fcenza\u00bb.<\/em><\/p>\n<p>Este a\u00f1o <strong>Juan Manuel Urtubey<\/strong> conform\u00f3 <em>\u201cAlternativa moderada\u201d<\/em>, un espacio que lo integra junto a <strong>Juan Schiaretti<\/strong>, el actual gobernador de C\u00f3rdoba. Ambos ya se postularon como precandidatos a presidentes para una eventual PASO.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/informedigital.com.ar\/imagenes\/2023\/05\/03\/0a67ed4e033210be2f4265f7229f645a.jpeg\" alt=\"Los Antigrieta se enfrentan para dirimir la grieta\" \/><\/p>\n<p>En di\u00e1logo con <strong>Cuatro Giros<\/strong> en <strong>Radio Late<\/strong>, Urtubey ratific\u00f3 la idea de dirimir las candidaturas en las primarias e invit\u00f3 a m\u00e1s dirigentes a sumarse al nuevo espacio pol\u00edtico que busca saltar la grieta. <em>\u201cSi pudiese haber m\u00e1s candidatos a presidente ser\u00eda buen\u00edsimo. Coincidimos en el modelo de pa\u00eds, pero creemos que la diversidad nos va a dar mas volumen electoral\u201d<\/em>, se\u00f1al\u00f3.<\/p>\n<p>En ese sentido, cont\u00f3 que <em>\u201cdel peronismo, Graciela Cama\u00f1o est\u00e1 trabajando activamente\u201d<\/em> y <em>\u201cen mayo veremos que muchos se sumen a este espacio\u201d<\/em> en alusi\u00f3n a que se integren dirigentes del GEN como <strong>Margarita Stolbizer<\/strong>.<\/p>\n<p>Para Urtubey, <em>\u201cel marco es muy diferente al de 2019\u201d<\/em> ya que <em>\u201chace 4 a\u00f1os, m\u00e1s all\u00e1 de la expectativa que gener\u00f3 nuestro espacio, el kirchnerismo se movi\u00f3 bien y ampli\u00f3 su base, tensionaban m\u00e1s los polos, hoy ese contexto es distinto porque ambos han fracasado\u201d<\/em>.<\/p>\n<p>Por otro lado, el ex gobernador salte\u00f1o expres\u00f3 su mirada sobre la situaci\u00f3n actual que atraviesa el pa\u00eds. <em>\u201cEl pa\u00eds se ha convertido literalmente en una sucursal de la timba financiera\u201d<\/em>, asegur\u00f3 y agreg\u00f3: <em>\u201cLa sociedad argentina no se banca m\u00e1s ajuste. En los \u00faltimos 70 a\u00f1os fuimos tan irresponsables que el Estado creci\u00f3 mas que la econom\u00eda, y eso tiene que ser al rev\u00e9s\u201d<\/em>.<\/p>\n<p>Sin embargo, y a pesar del descontento generalizado hacia la clase pol\u00edtica, advirti\u00f3: <em>\u201cGuarda de comerse el amague de que es el fin de la pol\u00edtica\u201d<\/em>. <em>\u201cLa Argentina tiene destino, pero hay que salir de este c\u00edrculo vicioso\u201d<\/em>, sintetiz\u00f3.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/static.eldiario.es\/clip\/e7c42fd2-7309-429c-bc99-b0641036f9b0_16-9-discover-aspect-ratio_default_0.jpg\" alt=\"Urtubey ratific\u00f3 su precandidatura presidencial y competir\u00e1 con Schiaretti en las PASO - elDiarioAR.com\" \/><\/p>\n<p>Por \u00faltimo, durante la entrevista con <strong>Sebasti\u00e1n Alonso<\/strong> y <strong>Eduardo Vitali<\/strong> dispar\u00f3 contra los dos partidos que canalizaron la polarizaci\u00f3n en la Argentina, Juntos por el Cambio y el <strong>Frente de Todos<\/strong>. Al respecto asegur\u00f3: <em>\u00abLos dos polos de la grieta fracasaron\u00bb<\/em>. Y fue \u00e1spero con el actual gobierno. Resalt\u00f3 que el FdT <em>\u00abhace el ajuste con la inflaci\u00f3n y la Argentina se parece m\u00e1s a una financiera que una f\u00e1brica\u00bb<\/em>.<\/p>\n<p><em>\u00abComo peronista, lo del kirchnerismo me da verg\u00fcenza\u00bb<\/em>, remat\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ex gobernador de Salta vuelve a ser parte de un armado electoral que pretende salir de la polarizaci\u00f3n del Frente de Todos y de Juntos por el Cambio, al igual que en 2019 cuando acompa\u00f1\u00f3 a Lavagna en la f\u00f3rmula presidencial. Fue dur\u00edsimo contra&#8230;<\/p>\n","protected":false},"author":4,"featured_media":6334,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,770],"tags":[1231,338,795,800,880,879,876,334,878,877,875],"_links":{"self":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/6333"}],"collection":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/comments?post=6333"}],"version-history":[{"count":4,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/6333\/revisions"}],"predecessor-version":[{"id":6342,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/posts\/6333\/revisions\/6342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media\/6334"}],"wp:attachment":[{"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/media?parent=6333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/categories?post=6333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cuatrogiros.com\/4G\/wp-json\/wp\/v2\/tags?post=6333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}